{"id":3133,"date":"2022-02-13T15:46:59","date_gmt":"2022-02-13T18:46:59","guid":{"rendered":"https:\/\/staging.golfinhorotador.org.br\/?p=3133"},"modified":"2025-08-11T15:51:58","modified_gmt":"2025-08-11T18:51:58","slug":"encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07","status":"publish","type":"post","link":"https:\/\/staging.golfinhorotador.org.br\/en\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/","title":{"rendered":"Encontro com os Albatrozes <br>\u2013 Podcast Golfinhos de Noronha #07"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3133\" class=\"elementor elementor-3133\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-570df822 e-flex e-con-boxed e-con e-parent\" data-id=\"570df822\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb8e508 elementor-widget elementor-widget-html\" data-id=\"cb8e508\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<iframe style=\"width: 100%; height: 200px;\" src=\"https:\/\/player.captivate.fm\/episode\/9278a904-39df-4c25-928b-604745560ace\" frameborder=\"no\" scrolling=\"no\" seamless=\"\"><\/iframe>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34df8e47 elementor-widget elementor-widget-text-editor\" data-id=\"34df8e47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ser\u00e1 que voc\u00ea conhece esses viajantes oce\u00e2nicos? Um dos amigos do golfinho-rotador, que infelizmente est\u00e1 amea\u00e7ado de extin\u00e7\u00e3o. Mergulhe com a Rede Biomar, o @projetoalbatroz e seus parceiros e fa\u00e7a parte da nossa nobre miss\u00e3o em conservar a biodiversidade dos oceanos!<\/p><p>Esse epis\u00f3dio conta com a participa\u00e7\u00e3o de pessoas e institui\u00e7\u00f5es que dedicam sua vida em preservar as aves marinhas: <a href=\"https:\/\/www.instagram.com\/projetoalbatroz\/\" target=\"_blank\" rel=\"noopener\">@projetoalbatroz<\/a> <a href=\"https:\/\/www.instagram.com\/icmbio.cemave\/\" target=\"_blank\" rel=\"noopener\">@icmbio.cemave<\/a> <a href=\"https:\/\/www.instagram.com\/rehurtado9\/\" target=\"_blank\" rel=\"noopener\">@rehurtado9<\/a> <a href=\"https:\/\/www.instagram.com\/nevestatiana\/\" target=\"_blank\" rel=\"noopener\">@nevestatiana<\/a> <a href=\"https:\/\/www.instagram.com\/pereiraserafini\/\" target=\"_blank\" rel=\"noopener\">@pereiraserafini<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e343220 elementor-widget elementor-widget-gallery\" data-id=\"e343220\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;aspect_ratio&quot;:&quot;9:16&quot;,&quot;image_hover_animation&quot;:&quot;grow&quot;,&quot;overlay_title&quot;:&quot;caption&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns&quot;:4,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR07-Cynthia.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e343220\" data-elementor-lightbox-title=\"PGR07-Cynthia\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzEzNSwidXJsIjoiaHR0cHM6XC9cL3N0YWdpbmcuZ29sZmluaG9yb3RhZG9yLm9yZy5iclwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDhcL1BHUjA3LUN5bnRoaWEuanBnIiwic2xpZGVzaG93IjoiZTM0MzIyMCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR07-Cynthia.jpg\" data-width=\"933\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tCynthia Gerling\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR07-Patricia.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e343220\" data-elementor-lightbox-title=\"PGR07-Patricia\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzEzNiwidXJsIjoiaHR0cHM6XC9cL3N0YWdpbmcuZ29sZmluaG9yb3RhZG9yLm9yZy5iclwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDhcL1BHUjA3LVBhdHJpY2lhLmpwZyIsInNsaWRlc2hvdyI6ImUzNDMyMjAifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR07-Patricia.jpg\" data-width=\"640\" data-height=\"640\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tPatricia Pereira Serafini\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR07-Re-Hurtado-1024x942-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e343220\" data-elementor-lightbox-title=\"PGR07-Re-Hurtado-1024x942\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzEzNywidXJsIjoiaHR0cHM6XC9cL3N0YWdpbmcuZ29sZmluaG9yb3RhZG9yLm9yZy5iclwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDhcL1BHUjA3LVJlLUh1cnRhZG8tMTAyNHg5NDItMS5qcGciLCJzbGlkZXNob3ciOiJlMzQzMjIwIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR07-Re-Hurtado-1024x942-1.jpg\" data-width=\"1024\" data-height=\"942\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tRenata Hurtado\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR07-tatiana-neves-1024x681-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"e343220\" data-elementor-lightbox-title=\"PGR07-tatiana-neves-1024x681\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzEzOCwidXJsIjoiaHR0cHM6XC9cL3N0YWdpbmcuZ29sZmluaG9yb3RhZG9yLm9yZy5iclwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDhcL1BHUjA3LXRhdGlhbmEtbmV2ZXMtMTAyNHg2ODEtMS5qcGciLCJzbGlkZXNob3ciOiJlMzQzMjIwIn0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/PGR07-tatiana-neves-1024x681-1.jpg\" data-width=\"1024\" data-height=\"681\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__title\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tTatiana Neves\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4035825 elementor-widget elementor-widget-text-editor\" data-id=\"4035825\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \"><div class=\"wpb_wrapper\"><p><strong>Cynthia Gerling:<\/strong>\u00a0coordenadora de Educomunica\u00e7\u00e3o Ambiental \u00e9 Sustentabilidade do Projeto Golfinho Rotador.<br \/>instagram:\u00a0<a href=\"https:\/\/www.instagram.com\/cynthiagerling\/\" target=\"_blank\" rel=\"noopener\">@cynthiagerling<\/a><\/p><p><strong>Tatiana Neves:<\/strong>\u00a0bi\u00f3loga, mestre em Oceanografia Biol\u00f3gica e especialista em aves marinhas. Fundou o Projeto Albatroz h\u00e1 31 anos em Santos (SP) para trabalhar pela conserva\u00e7\u00e3o deste albatrozes e petr\u00e9is que interagem com barcos de pesca de espinhel nas \u00e1guas brasileiras. \u00c9 Coordenadora Geral do Projeto Albatroz, Vice-Presidente do Comit\u00ea Assessor do Acordo para a Conserva\u00e7\u00e3o de Albatrozes e Petr\u00e9is (ACAP) e representante do Projeto Albatroz como coordenador executivo no Plano de A\u00e7\u00e3o Nacional para a Conserva\u00e7\u00e3o de Albatrozes e Petr\u00e9is (PLANACAP).<br \/>Instagram:\u00a0<a href=\"https:\/\/www.instagram.com\/nevestatiana\/\" target=\"_blank\" rel=\"noopener\">@nevestatiana<\/a><\/p><p><strong>Renata Hurtado:<\/strong>\u00a0M\u00e9dica Veterin\u00e1ria especializada em animais marinhos, Doutora pelo Departamento de Medicina Veterin\u00e1ria Preventiva e Sa\u00fade Animal (VPS) da Faculdade de Medicina Veterin\u00e1ria e Zootecnia da Universidade de S\u00e3o Paulo (FMVZ-USP), p\u00f3s-graduanda em Anestesiologia Veterin\u00e1ria, Pesquisadora Associada \u00e0 Southern African Foundation for the Conservation of Coastal Birds (SANCCOB) e Diretora Cient\u00edfica da Associa\u00e7\u00e3o Brasileira de Veterin\u00e1rios de Animais Selvagens (ABRAVAS). Articuladora do PLANACAP, editora do Livro \u201cReabilita\u00e7\u00e3o de Procellariiformes (albatroz, petrel, pardela)\u201d<br \/>Instagram:\u00a0<a href=\"https:\/\/www.instagram.com\/rehurtado9\/\" target=\"_blank\" rel=\"noopener\">@rehurtado9<\/a><\/p><p><strong>Patricia Pereira Serafini:<\/strong>\u00a0m\u00e9dica veterin\u00e1ria e analista ambiental do Centro Nacional de Pesquisa e Conserva\u00e7\u00e3o de Aves Silvestres do ICMBio (CEMAVE\/ICMBio). Atuo na co-coordena\u00e7\u00e3o do Grupo de Trabalho de Popula\u00e7\u00f5es e Estado de Conserva\u00e7\u00e3o do Acordo Internacional para a Conserva\u00e7\u00e3o dos Albatrozes e Petr\u00e9is (ACAP) e sou conselheira cient\u00edfica da Conven\u00e7\u00e3o sobre Esp\u00e9cies Migrat\u00f3rias (CMS\/ONU).<br \/>Instagram:\u00a0<a href=\"https:\/\/www.instagram.com\/pereiraserafini\/\" target=\"_blank\" rel=\"noopener\">@pereiraserafini<\/a><\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbb5106 elementor-widget elementor-widget-template\" data-id=\"bbb5106\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"2784\" class=\"elementor elementor-2784\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63d29cb1 e-flex e-con-boxed e-con e-parent\" data-id=\"63d29cb1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5df0ef02 elementor-widget elementor-widget-heading\" data-id=\"5df0ef02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Sobre o Canal Golfinhos de Noronha\n<\/h5>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15b5cbe5 e-con-full e-flex e-con e-child\" data-id=\"15b5cbe5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5de369f1 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"5de369f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/staging.golfinhorotador.org.br\/conteudo\/podcast\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2021\/04\/Logo-Podcast-Golfinhos-de-Noronha.png\" class=\"attachment-large size-large wp-image-6067\" alt=\"\" srcset=\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2021\/04\/Logo-Podcast-Golfinhos-de-Noronha.png 512w, https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2021\/04\/Logo-Podcast-Golfinhos-de-Noronha-300x300.png 300w, https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2021\/04\/Logo-Podcast-Golfinhos-de-Noronha-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18296881 elementor-widget elementor-widget-text-editor\" data-id=\"18296881\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Apaixonados pela conserva\u00e7\u00e3o dos golfinhos, do oceano e de Fernando de Noronha. Somos o Projeto Golfinho Rotador, que nasceu no Mirante dos Golfinhos em Fernando de Noronha em 23 de agosto de 1990. Ap\u00f3s tantos anos de trabalho nos tornamos um PELD (Programa de Pesquisa Ecol\u00f3gica de Longa Dura\u00e7\u00e3o. Nossos pilares s\u00e3o: pesquisa, educa\u00e7\u00e3o ambiental, envolvimento comunit\u00e1rio e sustentabilidade.<\/p><p>E voc\u00ea, \u00e9 nosso parceiro ideal! Mergulhe conosco nesse mundo azul.<\/p><p>O Podcast Golfinhos de Noronha conta com um patroc\u00ednio da Petrobras, por meio do programa Petrobras Socioambiental.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 que voc\u00ea conhece esses viajantes oce\u00e2nicos? Um dos amigos do golfinho-rotador, que infelizmente est\u00e1 amea\u00e7ado de extin\u00e7\u00e3o. Mergulhe com a Rede Biomar, o @projetoalbatroz e seus parceiros e fa\u00e7a parte da nossa nobre miss\u00e3o em conservar a biodiversidade dos oceanos! Esse epis\u00f3dio conta com a participa\u00e7\u00e3o de pessoas e institui\u00e7\u00f5es que dedicam sua vida [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcast"],"acf":{"exibir_imagem_destacada":"N\u00e3o"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encontro com os Albatrozes \u2013 Podcast Golfinhos de Noronha #07 - Projeto Golfinho Rotador<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encontro com os Albatrozes \u2013 Podcast Golfinhos de Noronha #07 - Projeto Golfinho Rotador\" \/>\n<meta property=\"og:description\" content=\"Ser\u00e1 que voc\u00ea conhece esses viajantes oce\u00e2nicos? Um dos amigos do golfinho-rotador, que infelizmente est\u00e1 amea\u00e7ado de extin\u00e7\u00e3o. Mergulhe com a Rede Biomar, o @projetoalbatroz e seus parceiros e fa\u00e7a parte da nossa nobre miss\u00e3o em conservar a biodiversidade dos oceanos! Esse epis\u00f3dio conta com a participa\u00e7\u00e3o de pessoas e institui\u00e7\u00f5es que dedicam sua vida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/\" \/>\n<meta property=\"og:site_name\" content=\"Projeto Golfinho Rotador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-13T18:46:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T18:51:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/pgr-podcast-07-destaque-1400.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Projeto Golfinho Rotador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@golfinhorotador\" \/>\n<meta name=\"twitter:site\" content=\"@golfinhorotador\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Projeto Golfinho Rotador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/\"},\"author\":{\"name\":\"Projeto Golfinho Rotador\",\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/#\/schema\/person\/31c9f545fc127c9e21fc1c5f001269db\"},\"headline\":\"Encontro com os Albatrozes \u2013 Podcast Golfinhos de Noronha #07\",\"datePublished\":\"2022-02-13T18:46:59+00:00\",\"dateModified\":\"2025-08-11T18:51:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/pgr-podcast-07-destaque-1400.jpg\",\"articleSection\":[\"Podcast\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/\",\"url\":\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/\",\"name\":\"Encontro com os Albatrozes \u2013 Podcast Golfinhos de Noronha #07 - Projeto Golfinho Rotador\",\"isPartOf\":{\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/pgr-podcast-07-destaque-1400.jpg\",\"datePublished\":\"2022-02-13T18:46:59+00:00\",\"dateModified\":\"2025-08-11T18:51:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#primaryimage\",\"url\":\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/pgr-podcast-07-destaque-1400.jpg\",\"contentUrl\":\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/pgr-podcast-07-destaque-1400.jpg\",\"width\":1400,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/staging.golfinhorotador.org.br\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encontro com os Albatrozes \u2013 Podcast Golfinhos de Noronha #07\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/#website\",\"url\":\"https:\/\/staging.golfinhorotador.org.br\/\",\"name\":\"Projeto Golfinho Rotador\",\"description\":\"Fernando de Noronha\",\"publisher\":{\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.golfinhorotador.org.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/#organization\",\"name\":\"Projeto Golfinho Rotador\",\"url\":\"https:\/\/staging.golfinhorotador.org.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/07\/Logo-PGR-2025-512.png\",\"contentUrl\":\"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/07\/Logo-PGR-2025-512.png\",\"width\":512,\"height\":512,\"caption\":\"Projeto Golfinho Rotador\"},\"image\":{\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813\",\"https:\/\/x.com\/golfinhorotador\",\"https:\/\/www.instagram.com\/golfinhorotador\/\",\"https:\/\/www.youtube.com\/channel\/UCYw-aMfBHbkUU_DimpWJzbw\",\"https:\/\/www.tiktok.com\/@golfinhorotador\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/staging.golfinhorotador.org.br\/#\/schema\/person\/31c9f545fc127c9e21fc1c5f001269db\",\"name\":\"Projeto Golfinho Rotador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g\",\"caption\":\"Projeto Golfinho Rotador\"},\"url\":\"https:\/\/staging.golfinhorotador.org.br\/en\/author\/projeto-golfinho-rotador\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encontro com os Albatrozes \u2013 Podcast Golfinhos de Noronha #07 - Projeto Golfinho Rotador","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Encontro com os Albatrozes \u2013 Podcast Golfinhos de Noronha #07 - Projeto Golfinho Rotador","og_description":"Ser\u00e1 que voc\u00ea conhece esses viajantes oce\u00e2nicos? Um dos amigos do golfinho-rotador, que infelizmente est\u00e1 amea\u00e7ado de extin\u00e7\u00e3o. Mergulhe com a Rede Biomar, o @projetoalbatroz e seus parceiros e fa\u00e7a parte da nossa nobre miss\u00e3o em conservar a biodiversidade dos oceanos! Esse epis\u00f3dio conta com a participa\u00e7\u00e3o de pessoas e institui\u00e7\u00f5es que dedicam sua vida [&hellip;]","og_url":"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/","og_site_name":"Projeto Golfinho Rotador","article_publisher":"https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813","article_published_time":"2022-02-13T18:46:59+00:00","article_modified_time":"2025-08-11T18:51:58+00:00","og_image":[{"width":1400,"height":1400,"url":"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/pgr-podcast-07-destaque-1400.jpg","type":"image\/jpeg"}],"author":"Projeto Golfinho Rotador","twitter_card":"summary_large_image","twitter_creator":"@golfinhorotador","twitter_site":"@golfinhorotador","twitter_misc":{"Written by":"Projeto Golfinho Rotador","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#article","isPartOf":{"@id":"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/"},"author":{"name":"Projeto Golfinho Rotador","@id":"https:\/\/staging.golfinhorotador.org.br\/#\/schema\/person\/31c9f545fc127c9e21fc1c5f001269db"},"headline":"Encontro com os Albatrozes \u2013 Podcast Golfinhos de Noronha #07","datePublished":"2022-02-13T18:46:59+00:00","dateModified":"2025-08-11T18:51:58+00:00","mainEntityOfPage":{"@id":"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/staging.golfinhorotador.org.br\/#organization"},"image":{"@id":"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/pgr-podcast-07-destaque-1400.jpg","articleSection":["Podcast"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/","url":"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/","name":"Encontro com os Albatrozes \u2013 Podcast Golfinhos de Noronha #07 - Projeto Golfinho Rotador","isPartOf":{"@id":"https:\/\/staging.golfinhorotador.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#primaryimage"},"image":{"@id":"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/pgr-podcast-07-destaque-1400.jpg","datePublished":"2022-02-13T18:46:59+00:00","dateModified":"2025-08-11T18:51:58+00:00","breadcrumb":{"@id":"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#primaryimage","url":"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/pgr-podcast-07-destaque-1400.jpg","contentUrl":"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/08\/pgr-podcast-07-destaque-1400.jpg","width":1400,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/staging.golfinhorotador.org.br\/2022\/02\/13\/encontro-com-os-albatrozes-podcast-golfinhos-de-noronha-07\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/staging.golfinhorotador.org.br\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Encontro com os Albatrozes \u2013 Podcast Golfinhos de Noronha #07"}]},{"@type":"WebSite","@id":"https:\/\/staging.golfinhorotador.org.br\/#website","url":"https:\/\/staging.golfinhorotador.org.br\/","name":"Projeto Golfinho Rotador","description":"Fernando de Noronha","publisher":{"@id":"https:\/\/staging.golfinhorotador.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.golfinhorotador.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/staging.golfinhorotador.org.br\/#organization","name":"Projeto Golfinho Rotador","url":"https:\/\/staging.golfinhorotador.org.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/staging.golfinhorotador.org.br\/#\/schema\/logo\/image\/","url":"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/07\/Logo-PGR-2025-512.png","contentUrl":"https:\/\/staging.golfinhorotador.org.br\/wp-content\/uploads\/2025\/07\/Logo-PGR-2025-512.png","width":512,"height":512,"caption":"Projeto Golfinho Rotador"},"image":{"@id":"https:\/\/staging.golfinhorotador.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Projeto-Golfinho-Rotador-155695874539813","https:\/\/x.com\/golfinhorotador","https:\/\/www.instagram.com\/golfinhorotador\/","https:\/\/www.youtube.com\/channel\/UCYw-aMfBHbkUU_DimpWJzbw","https:\/\/www.tiktok.com\/@golfinhorotador"]},{"@type":"Person","@id":"https:\/\/staging.golfinhorotador.org.br\/#\/schema\/person\/31c9f545fc127c9e21fc1c5f001269db","name":"Projeto Golfinho Rotador","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e2f6bba9197287956dc1c931a4caed810b09aec9b8f38aa913bd11926fd05d2?s=96&d=mm&r=g","caption":"Projeto Golfinho Rotador"},"url":"https:\/\/staging.golfinhorotador.org.br\/en\/author\/projeto-golfinho-rotador\/"}]}},"_links":{"self":[{"href":"https:\/\/staging.golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts\/3133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/staging.golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/staging.golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/comments?post=3133"}],"version-history":[{"count":4,"href":"https:\/\/staging.golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts\/3133\/revisions"}],"predecessor-version":[{"id":3142,"href":"https:\/\/staging.golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/posts\/3133\/revisions\/3142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/media\/3134"}],"wp:attachment":[{"href":"https:\/\/staging.golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/media?parent=3133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/staging.golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/categories?post=3133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/staging.golfinhorotador.org.br\/en\/wp-json\/wp\/v2\/tags?post=3133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}